{"id":241,"date":"2021-08-15T15:10:18","date_gmt":"2021-08-15T15:10:18","guid":{"rendered":"https:\/\/4overland.com\/?page_id=241"},"modified":"2025-06-17T07:55:37","modified_gmt":"2025-06-17T06:55:37","slug":"homepage","status":"publish","type":"page","link":"https:\/\/4overland.com\/en\/","title":{"rendered":"Homepage"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-bottom:50px;--awb-background-color:#ffffff;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h2 style=\"text-align: center;\">4Overland windows<\/h2>\n<\/div><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"800\" height=\"600\" title=\"Def_Finestra5\" src=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/Def_Finestra5-1.jpg\" alt class=\"img-responsive wp-image-228\" srcset=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/Def_Finestra5-1-200x150.jpg 200w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/Def_Finestra5-1-400x300.jpg 400w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/Def_Finestra5-1-600x450.jpg 600w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/Def_Finestra5-1.jpg 800w\" sizes=\"(max-width: 640px) 100vw, 600px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-xlarge button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#ffffff;--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:#005e38;--button_gradient_bottom_color:#005e38;--button_gradient_top_color_hover:#5aa86c;--button_gradient_bottom_color_hover:#5aa86c;\" target=\"_self\" href=\"https:\/\/4overland.com\/en\/windows\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">FIND OUT NOW<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><h2 style=\"text-align: center;\">4Overland roof windows<\/h2>\n<\/div><div class=\"fusion-image-element\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"800\" height=\"600\" title=\"obl\u00f2 chiuso\" src=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/oblo-chiuso.jpg\" alt class=\"img-responsive wp-image-225\" srcset=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/oblo-chiuso-200x150.jpg 200w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/oblo-chiuso-400x300.jpg 400w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/oblo-chiuso-600x450.jpg 600w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/oblo-chiuso.jpg 800w\" sizes=\"(max-width: 640px) 100vw, 600px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-xlarge button-custom fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#ffffff;--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:#005e38;--button_gradient_bottom_color:#005e38;--button_gradient_top_color_hover:#5aa86c;--button_gradient_bottom_color_hover:#5aa86c;\" target=\"_self\" href=\"https:\/\/4overland.com\/en\/roof-windows\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">FIND OUT NOW<\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:50px;--awb-padding-bottom:50px;--awb-background-color:#eaeaea;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\"><h2 style=\"text-align: center;\">Come to visit us at our stand!<\/h2>\n<\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-pagination\" style=\"--grid_separator_color:#ffffff;\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:20px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -20px !important; margin-right:-20px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-pagination fusion-no-meta-info fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-2 isotope fusion-blog-equal-heights\" data-pages=\"1\" data-grid-col-space=\"40\" style=\"margin: -20px -20px 0;min-height:500px;\"><article id=\"blog-1-post-345\" class=\"fusion-post-grid post-345 post type-post status-publish format-standard has-post-thumbnail hentry category-events-en\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #fffcfc;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#fffcfc;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"296\" height=\"150\" src=\"https:\/\/4overland.com\/wp-content\/uploads\/2025\/06\/logo-x150.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/4overland.com\/wp-content\/uploads\/2025\/06\/logo-x150-200x101.png 200w, https:\/\/4overland.com\/wp-content\/uploads\/2025\/06\/logo-x150.png 296w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 712px) 580px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/4overland.com\/en\/events-en\/abenteuer-und-allrad-2023-june-8th-11th-germany\/\">Abenteuer und Allrad 2026- June 4th\/7th &#8211; Germany<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/4overland.com\/wp-content\/uploads\/2025\/06\/logo-x150.png\" data-options=\"\" data-id=\"345\" data-rel=\"iLightbox[gallery]\" data-title=\"logo-x150\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t\t<a class=\"fusion-rollover-title-link\" href=\"https:\/\/4overland.com\/en\/events-en\/abenteuer-und-allrad-2023-june-8th-11th-germany\/\">\n\t\t\t\t\t\tAbenteuer und Allrad 2026- June 4th\/7th &#8211; Germany\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/4overland.com\/en\/category\/events-en\/\" rel=\"tag\">events<\/a><\/div>\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/4overland.com\/en\/events-en\/abenteuer-und-allrad-2023-june-8th-11th-germany\/\" aria-label=\"Abenteuer und Allrad 2026- June 4th\/7th &#8211; Germany\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t<div class=\"fusion-image-wrapper\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/4overland.com\/en\/events-en\/abenteuer-und-allrad-2023-june-8th-11th-germany\/\" aria-label=\"Abenteuer und Allrad 2026- June 4th\/7th &#8211; Germany\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750.jpg\" alt=\"\" class=\"wp-image-328\" role=\"presentation\" srcset=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750-200x150.jpg 200w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750-400x300.jpg 400w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750-600x450.jpg 600w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750-800x600.jpg 800w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750-1200x900.jpg 1200w, https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750.jpg 2048w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 712px) 580px, (min-width: 640px) 712px, \" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<a style=\"display:none;\" href=\"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/0e4dbda7-8000-44e8-ae94-e37ef5c28750.jpg\" data-rel=\"iLightbox[gallery345]\"  title=\"\" data-title=\"0e4dbda7-8000-44e8-ae94-e37ef5c28750\" data-caption=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 25px 25px;\"><div class=\"fusion-post-content post-content\"><h2 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/4overland.com\/en\/events-en\/abenteuer-und-allrad-2023-june-8th-11th-germany\/\">Abenteuer und Allrad 2026- June 4th\/7th &#8211; Germany<\/a><\/h2><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-241","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4Overland: accessories for 4x4 truck building<\/title>\n<meta name=\"description\" content=\"Products for the building of long travel truck cell. Windows, roof windows, doors (external and internal passage cabine\/cell) and hatches.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/4overland.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4Overland: accessories for 4x4 truck building\" \/>\n<meta property=\"og:description\" content=\"Products for the building of long travel truck cell. Windows, roof windows, doors (external and internal passage cabine\/cell) and hatches.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/4overland.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"4Overland\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-17T06:55:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/\",\"url\":\"https:\\\/\\\/4overland.com\\\/en\\\/\",\"name\":\"4Overland: accessories for 4x4 truck building\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#website\"},\"datePublished\":\"2021-08-15T15:10:18+00:00\",\"dateModified\":\"2025-06-17T06:55:37+00:00\",\"description\":\"Products for the building of long travel truck cell. Windows, roof windows, doors (external and internal passage cabine\\\/cell) and hatches.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/4overland.com\\\/en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/4overland.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/4overland.com\\\/en\\\/\",\"name\":\"4Overland\",\"description\":\"Accessories for 4x4 truck building\",\"publisher\":{\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/4overland.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#organization\",\"name\":\"4Overland\",\"url\":\"https:\\\/\\\/4overland.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/4overland.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/4overland_logo-e1628276428602.jpg\",\"contentUrl\":\"https:\\\/\\\/4overland.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/4overland_logo-e1628276428602.jpg\",\"width\":100,\"height\":60,\"caption\":\"4Overland\"},\"image\":{\"@id\":\"https:\\\/\\\/4overland.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4Overland: accessories for 4x4 truck building","description":"Products for the building of long travel truck cell. Windows, roof windows, doors (external and internal passage cabine\/cell) and hatches.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/4overland.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"4Overland: accessories for 4x4 truck building","og_description":"Products for the building of long travel truck cell. Windows, roof windows, doors (external and internal passage cabine\/cell) and hatches.","og_url":"https:\/\/4overland.com\/en\/","og_site_name":"4Overland","article_modified_time":"2025-06-17T06:55:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/4overland.com\/en\/","url":"https:\/\/4overland.com\/en\/","name":"4Overland: accessories for 4x4 truck building","isPartOf":{"@id":"https:\/\/4overland.com\/en\/#website"},"datePublished":"2021-08-15T15:10:18+00:00","dateModified":"2025-06-17T06:55:37+00:00","description":"Products for the building of long travel truck cell. Windows, roof windows, doors (external and internal passage cabine\/cell) and hatches.","breadcrumb":{"@id":"https:\/\/4overland.com\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/4overland.com\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/4overland.com\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/4overland.com\/en\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/4overland.com\/en\/#website","url":"https:\/\/4overland.com\/en\/","name":"4Overland","description":"Accessories for 4x4 truck building","publisher":{"@id":"https:\/\/4overland.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/4overland.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/4overland.com\/en\/#organization","name":"4Overland","url":"https:\/\/4overland.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/4overland.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/4overland_logo-e1628276428602.jpg","contentUrl":"https:\/\/4overland.com\/wp-content\/uploads\/2021\/08\/4overland_logo-e1628276428602.jpg","width":100,"height":60,"caption":"4Overland"},"image":{"@id":"https:\/\/4overland.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/pages\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":7,"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/pages\/241\/revisions"}],"predecessor-version":[{"id":577,"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/pages\/241\/revisions\/577"}],"wp:attachment":[{"href":"https:\/\/4overland.com\/en\/wp-json\/wp\/v2\/media?parent=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}